{"id":240008,"date":"2023-06-30T14:15:02","date_gmt":"2023-06-30T14:15:02","guid":{"rendered":"https:\/\/teora-xr.de\/protezione-dei-dati\/"},"modified":"2025-04-08T11:43:13","modified_gmt":"2025-04-08T11:43:13","slug":"protezione-dei-dati","status":"publish","type":"page","link":"https:\/\/teora-xr.de\/en\/protezione-dei-dati\/?lang=it","title":{"rendered":"Protezione dei dati"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; fullwidth=&#8220;on&#8220; _builder_version=&#8220;4.20.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220; da_disable_devices=&#8220;off|off|off&#8220;][et_pb_fullwidth_image src=&#8220;https:\/\/teora-xr.de\/wp-content\/uploads\/sites\/3\/2025\/04\/Informativa-sulla-privacy.png&#8220; alt=&#8220;Dichiarazione di protezione dei dati&#8220; title_text=&#8220;Informativa sulla privacy&#8220; _builder_version=&#8220;4.20.4&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;|||||true&#8220; custom_margin_tablet=&#8220;|||||true&#8220; custom_margin_phone=&#8220;80px||50px||false|true&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Sektion&#8220; _builder_version=&#8220;4.20.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220; da_disable_devices=&#8220;off|off|off&#8220;][et_pb_row _builder_version=&#8220;4.20.4&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;||70px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.20.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Manrope||||||||&#8220; text_text_color=&#8220;#001A51&#8243; text_font_size=&#8220;17px&#8220; text_line_height=&#8220;1.9em&#8220; header_font=&#8220;Manrope||||||||&#8220; header_text_color=&#8220;#001A51&#8243; header_line_height=&#8220;1.9em&#8220; header_2_font=&#8220;Manrope||||||||&#8220; header_2_line_height=&#8220;1.9em&#8220; header_3_font=&#8220;Manrope||||||||&#8220; header_3_line_height=&#8220;1.9em&#8220; text_orientation=&#8220;justified&#8220; custom_margin=&#8220;||70px||false|false&#8220; custom_padding=&#8220;||||false|false&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h1 style=\"text-align: left;\">Informativa sulla privacy<\/h1>\n<h2 style=\"text-align: left;\">1. la protezione dei dati in sintesi<\/h2>\n<h3 style=\"text-align: left;\">Informazioni generali<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Le seguenti informazioni forniscono una panoramica di ci\u00f2 che accade ai tuoi dati personali quando visiti questo sito web. I dati personali sono tutti i dati con i quali puoi essere identificato personalmente. Informazioni dettagliate sul tema della protezione dei dati sono disponibili nella nostra informativa sulla privacy riportata in calce al presente testo.<\/p>\n<h3 style=\"text-align: left;\">Raccolta di dati su questo sito web<\/h3>\n<h4 style=\"text-align: left;\">Chi \u00e8 responsabile della raccolta dei dati su questo sito?<\/h4>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Il trattamento dei dati su questo sito web \u00e8 effettuato dall&#8217;operatore del sito. Puoi trovare i loro dettagli di contatto nella sezione &#8222;Titolare del trattamento&#8220; di questa informativa sulla privacy.<\/p>\n<h4 style=\"text-align: left;\">Come raccogliamo i tuoi dati?<\/h4>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Da un lato, alcuni dati vengono raccolti automaticamente o con il tuo consenso dai nostri sistemi informatici quando visiti il sito web. Si tratta principalmente di dati tecnici (ad esempio il browser internet, il sistema operativo o l&#8217;ora di visualizzazione della pagina). <br \/>Questi dati vengono raccolti automaticamente non appena accedi al sito, mentre i tuoi dati vengono raccolti quando ce li fornisci. Ad esempio, i dati inseriti dall&#8217;utente nel modulo di contatto.<\/p>\n<h4 style=\"text-align: left;\">Per cosa utilizziamo i tuoi dati?<\/h4>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Una parte dei dati pu\u00f2 essere utilizzata per analizzare il comportamento degli utenti. Altri dati vengono utilizzati per garantire la fornitura senza errori del sito web.<\/p>\n<h4 style=\"text-align: left;\">Quali diritti hai in merito ai tuoi dati?<\/h4>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Hai il diritto di ricevere gratuitamente in qualsiasi momento informazioni sull&#8217;origine, il destinatario e lo scopo dei tuoi dati personali memorizzati. Hai inoltre il diritto di richiedere la correzione o la cancellazione di tali dati. Puoi revocare il consenso al trattamento dei dati precedentemente prestato in qualsiasi momento per il futuro. Hai inoltre il diritto di richiedere la limitazione del trattamento dei tuoi dati personali in determinate circostanze. Inoltre, hai il diritto di presentare un reclamo all&#8217;autorit\u00e0 di vigilanza competente.<\/p>\n<p style=\"text-align: left;\">Non esitare a contattarci in qualsiasi momento se hai ulteriori domande sul tema della protezione dei dati.<\/p>\n<h3 style=\"text-align: left;\">Strumenti di analisi e strumenti di fornitori terzi<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Quando visiti questo sito web, il tuo comportamento di navigazione pu\u00f2 essere valutato statisticamente.<br \/>\nQuesto viene fatto principalmente con i cosiddetti programmi di analisi. <\/p>\n<p style=\"text-align: left;\">Informazioni dettagliate sui programmi di analisi utilizzati sono disponibili nella seguente informativa sulla privacy.<\/p>\n<h2 style=\"text-align: left;\">2. hosting<\/h2>\n<p style=\"text-align: left;\">Il contenuto del nostro sito web \u00e8 ospitato dal seguente provider:<\/p>\n<h3 style=\"text-align: left;\">All-Inkl<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Il fornitore \u00e8 ALL-INKL.COM &#8211; Neue Medien M\u00fcnnich, Inh. Ren\u00e9 M\u00fcnnich, Hauptstra\u00dfe 68, 02742 Friedersdorf (di seguito All-Inkl). I dettagli possono essere trovati nell&#8217;informativa sulla privacy di All-Inkl: <a href=\"https:\/\/all-inkl.com\/datenschutzinformationen\/\">https:\/\/all-inkl.com\/datenschutzinformationen\/<\/a>.<\/p>\n<p style=\"text-align: left;\">L&#8217;utilizzo di All-Inkl si basa sull&#8217;Art. 6 comma. 1 lit. f GDPR. Abbiamo un interesse legittimo a garantire che il nostro sito web venga visualizzato nel modo pi\u00f9 affidabile possibile. Se \u00e8 stato richiesto un consenso corrispondente, il trattamento viene effettuato esclusivamente sulla base dell&#8217;Art. 6 para. 1 lit. a GDPR e \u00a7 25 para. 1 TTDSG, nella misura in cui il consenso includa la memorizzazione di cookie o l&#8217;accesso a informazioni nel dispositivo finale dell&#8217;utente (ad esempio, l&#8217;impronta digitale del dispositivo) ai sensi del TTDSG. Il consenso pu\u00f2 essere revocato in qualsiasi momento.<\/p>\n<h4 style=\"text-align: left;\">Elaborazione dell&#8217;ordine<\/h4>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Abbiamo stipulato un accordo per l&#8217;elaborazione degli ordini (AVV) per l&#8217;utilizzo del servizio di cui sopra. Si tratta di un contratto prescritto dalla legge sulla protezione dei dati, che garantisce che il titolare del trattamento dei dati personali dei visitatori del nostro sito web avvenga solo in conformit\u00e0 alle nostre istruzioni e nel rispetto del GDPR.<\/p>\n<h2 style=\"text-align: left;\">3 Note generali e informazioni obbligatorie<\/h2>\n<h3 style=\"text-align: left;\">Protezione dei dati<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Trattiamo i tuoi dati personali in modo confidenziale e in conformit\u00e0 alle norme di legge sulla protezione dei dati e alla presente informativa sulla privacy. Gli operatori di queste pagine prendono molto sul serio la protezione dei tuoi dati personali.<\/p>\n<p style=\"text-align: left;\">Quando utilizzi questo sito web, vengono raccolti diversi dati personali.<br \/>\nI dati personali sono dati che possono essere utilizzati per identificarti personalmente.<br \/>\nLa presente informativa sulla privacy spiega quali dati raccogliamo e per quali scopi li utilizziamo.<br \/>\nSpiega inoltre come e per quale scopo vengono raccolti.   <\/p>\n<p style=\"text-align: left;\">Desideriamo sottolineare che la trasmissione dei dati su Internet (ad esempio quando si comunica via e-mail) pu\u00f2 essere soggetta a vulnerabilit\u00e0 di sicurezza.<br \/>\nNon \u00e8 possibile proteggere completamente i dati dall&#8217;accesso di terzi. <\/p>\n<h3 style=\"text-align: left;\">Nota sull&#8217;ente responsabile<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Il responsabile del trattamento dei dati su questo sito web \u00e8<\/p>\n<p style=\"text-align: left;\">living brain GmbH<\/p>\n<p style=\"text-align: left;\">Friedrich-Ebert-Anlage 27<\/p>\n<p style=\"text-align: left;\">69117 Heidelberg<\/p>\n<p style=\"text-align: left;\">Telefono: +49 173 7808422<\/p>\n<p data-pm-slice=\"1 1 []\">Per qualsiasi dubbio sulla protezione dei dati personali, contatta il nostro indirizzo e-mail dedicato: <a href=\"mailto:dataprotection@livingbrain.de\">dataprotection@livingbrain.de<\/a><\/p>\n<p style=\"text-align: left;\">Il responsabile del trattamento \u00e8 la persona fisica o giuridica che, da sola o insieme ad altri, determina le finalit\u00e0 e i mezzi del trattamento dei dati personali (ad esempio nomi, indirizzi e-mail, ecc.).<\/p>\n<h3 style=\"text-align: left;\">Durata della conservazione<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">A meno che non sia stato specificato un periodo di conservazione pi\u00f9 specifico nella presente informativa sulla privacy, i tuoi dati personali rimarranno presso di noi fino a quando lo scopo del trattamento dei dati non sar\u00e0 pi\u00f9 applicabile. Se fai valere una richiesta giustificata di cancellazione o revochi il tuo consenso al trattamento dei dati, i tuoi dati saranno cancellati, a meno che non ci siano altri motivi legalmente consentiti per conservare i tuoi dati personali (ad esempio, periodi di conservazione previsti dalla legge fiscale o commerciale); in quest&#8217;ultimo caso, la cancellazione avverr\u00e0 dopo che tali motivi non saranno pi\u00f9 validi.<\/p>\n<h3 style=\"text-align: left;\">Informazioni generali sulla base giuridica del trattamento dei dati su questo sito web<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Se hai acconsentito al trattamento dei dati, trattiamo i tuoi dati personali sulla base dell&#8217;Art. 6 para. 1 lit. a GDPR e l&#8217;art. 9 par. 2 litri. a GDPR, nella misura in cui le categorie particolari di dati ai sensi dell&#8217;art. 9 para. 1 GDPR sono trattati. In caso di consenso esplicito al trasferimento dei dati personali a paesi terzi, il trattamento dei dati viene effettuato anche sulla base dell&#8217;Art. 49 para. 1 lit. a GDPR. Se hai acconsentito alla memorizzazione dei cookie o all&#8217;accesso alle informazioni nel tuo dispositivo finale (ad esempio tramite il fingerprinting del dispositivo), il trattamento dei dati viene effettuato anche sulla base dell&#8217;articolo 25 (1) del GDPR. 1 TTDSG. Il consenso pu\u00f2 essere revocato in qualsiasi momento. Se i tuoi dati sono necessari per l&#8217;adempimento del contratto o per l&#8217;attuazione di misure precontrattuali, trattiamo i tuoi dati sulla base dell&#8217;art. 6 comma. 1 lit. b GDPR. Inoltre, trattiamo i tuoi dati se ci\u00f2 \u00e8 necessario per adempiere a un obbligo legale sulla base dell&#8217;Art. 6 para. 1 lit. c GDPR. Il trattamento dei dati pu\u00f2 anche essere basato sul nostro legittimo interesse in conformit\u00e0 con l&#8217;art. 6, par. 1 lit. f \u00c8 necessario eseguire il DSGVO. Le informazioni sulle basi legali pertinenti in ogni singolo caso sono fornite nei paragrafi successivi della presente informativa sulla privacy.<\/p>\n<h3 style=\"text-align: left;\">Nota sul trasferimento dei dati negli Stati Uniti e in altri paesi terzi<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Tra l&#8217;altro, utilizziamo strumenti di aziende con sede negli Stati Uniti o in altri paesi terzi che non sono sicuri ai sensi della legge sulla protezione dei dati. Se questi strumenti sono attivi, i tuoi dati personali potrebbero essere trasferiti in questi paesi terzi e l\u00ec trattati. Vorremmo sottolineare che in questi paesi non \u00e8 possibile garantire un livello di protezione dei dati paragonabile a quello dell&#8217;UE. Ad esempio, le aziende statunitensi sono obbligate a consegnare i dati personali alle autorit\u00e0 di sicurezza senza che tu, in quanto interessato, possa intraprendere un&#8217;azione legale. Non si pu\u00f2 quindi escludere che le autorit\u00e0 statunitensi (ad esempio i servizi segreti) possano elaborare, analizzare e conservare in modo permanente i tuoi dati su server statunitensi a scopo di sorveglianza. Non abbiamo alcuna influenza su queste attivit\u00e0 di elaborazione.<\/p>\n<h3 style=\"text-align: left;\">Destinatari dei dati personali<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Nell&#8217;ambito delle nostre attivit\u00e0 commerciali, collaboriamo con diverse organizzazioni esterne. In alcuni casi, \u00e8 necessario trasferire i dati personali a questi enti esterni. Trasmettiamo i dati personali a enti esterni solo se ci\u00f2 \u00e8 necessario per l&#8217;adempimento di un contratto, se siamo obbligati per legge a farlo (ad esempio trasmettendo i dati alle autorit\u00e0 fiscali), se abbiamo un interesse legittimo ai sensi dell&#8217;art. 6 par. 1 lit. a GDPR o se abbiamo un interesse legittimo nel trattamento dei dati personali. 1 lit. f GDPR o se un&#8217;altra base giuridica consente il trasferimento dei dati. Quando utilizziamo i responsabili del trattamento, trasmettiamo i dati personali dei nostri clienti solo sulla base di un contratto valido per l&#8217;elaborazione degli ordini. In caso di trattamento congiunto, viene stipulato un accordo di trattamento congiunto.<\/p>\n<h3 style=\"text-align: left;\">Revoca del consenso al trattamento dei dati<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Molte operazioni di trattamento dei dati sono possibili solo con il tuo consenso espresso.<br \/>\nPuoi revocare il tuo consenso in qualsiasi momento.<br \/>\nLa legalit\u00e0 del trattamento dei dati effettuato fino alla revoca rimane inalterata.  <\/p>\n<h3 style=\"text-align: left;\">Diritto di opporsi alla raccolta dei dati in casi particolari e al marketing diretto (Art. 21 GDPR)<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Se il trattamento dei dati si basa sull&#8217;Art. 6 para. 1 lit. e o f del GDPR, hai il diritto di opporti in qualsiasi momento al trattamento dei tuoi dati personali per motivi legati alla tua situazione particolare. Questo vale anche per la profilazione basata su queste disposizioni. La base giuridica su cui si fonda il trattamento \u00e8 riportata nella presente informativa sulla privacy. Se presenti un&#8217;obiezione, non tratteremo pi\u00f9 i tuoi dati personali in questione, a meno che non possiamo dimostrare l&#8217;esistenza di motivi legittimi e impellenti per il trattamento che prevalgono sui tuoi interessi, diritti e libert\u00e0 o che il trattamento serva per l&#8217;istituzione, l&#8217;esercizio o la difesa di rivendicazioni legali (obiezione ai sensi dell&#8217;art. 21 (1) GDPR).<\/p>\n<p style=\"text-align: left;\">Nel caso in cui i tuoi dati personali siano trattati per finalit\u00e0 di marketing diretto, hai il diritto di opporti in qualsiasi momento al trattamento dei dati personali che ti riguardano per tale marketing, che include la profilazione nella misura in cui \u00e8 correlata a tale marketing diretto. In caso di opposizione, i tuoi dati personali non saranno pi\u00f9 utilizzati per finalit\u00e0 di marketing diretto (opposizione ai sensi dell&#8217;art. 21 par. 2 GDPR).<\/p>\n<h3 style=\"text-align: left;\">Diritto di proporre reclamo all&#8217;autorit\u00e0 di vigilanza competente<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">In caso di violazioni del GDPR, gli interessati hanno il diritto di proporre reclamo a un&#8217;autorit\u00e0 di controllo, in particolare nello Stato membro in cui risiedono abitualmente, lavorano o in cui si \u00e8 verificata la presunta violazione.<br \/>\nIl diritto di presentare un reclamo non pregiudica eventuali altri rimedi amministrativi o giudiziari. <\/p>\n<h3 style=\"text-align: left;\">Diritto alla portabilit\u00e0 dei dati<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Hai il diritto di ottenere che i dati che trattiamo automaticamente sulla base del tuo consenso o in adempimento di un contratto vengano consegnati a te o a una terza parte in un formato comunemente utilizzato e leggibile da una macchina. Se richiedi il trasferimento diretto dei dati a un altro responsabile del trattamento, ci\u00f2 avverr\u00e0 solo se tecnicamente fattibile.<\/p>\n<h3 style=\"text-align: left;\">Informazioni, correzione e cancellazione<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Nell&#8217;ambito delle disposizioni di legge applicabili, hai il diritto di ottenere in qualsiasi momento informazioni gratuite sui tuoi dati personali memorizzati, sulla loro origine e sul loro destinatario e sullo scopo del trattamento dei dati e, se necessario, il diritto alla correzione o alla cancellazione di tali dati.<br \/>\nPuoi contattarci in qualsiasi momento se hai ulteriori domande sul tema dei dati personali. <\/p>\n<h3 style=\"text-align: left;\">Diritto alla limitazione del trattamento<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Hai il diritto di richiedere la limitazione del trattamento dei tuoi dati personali. Contattaci in qualsiasi momento. Il diritto alla limitazione del trattamento esiste nei seguenti casi:<\/p>\n<ul class=\"ak-ul\" style=\"text-align: left;\">\n<li>Se il trattamento dei tuoi dati personali era\/\u00e8 illegale, puoi richiedere la limitazione del trattamento dei dati invece della cancellazione.<\/li>\n<li>Se hai presentato un&#8217;obiezione ai sensi dell&#8217;Art. 21 para.<br \/>\n1 GDPR, \u00e8 necessario trovare un equilibrio tra i tuoi interessi e i nostri.<br \/>\nFinch\u00e9 non sar\u00e0 stato stabilito quali interessi prevalgono, hai il diritto di richiedere la limitazione del trattamento dei tuoi dati personali.  <\/li>\n<li>Se non abbiamo pi\u00f9 bisogno dei tuoi dati personali, ma ti servono per l&#8217;esercizio, la difesa o l&#8217;affermazione di diritti legali, hai il diritto di richiedere la limitazione del trattamento dei tuoi dati personali invece della loro cancellazione.<\/li>\n<li>Se contesti l&#8217;accuratezza dei tuoi dati personali da noi memorizzati, in genere abbiamo bisogno di tempo per verificarla.<br \/>\nPer la durata della verifica, hai il diritto di richiedere la limitazione del trattamento dei tuoi dati personali. <\/li>\n<\/ul>\n<p style=\"text-align: left;\">Se hai limitato il trattamento dei tuoi dati personali, questi &#8211; a parte la loro conservazione &#8211; potranno essere trattati solo con il tuo consenso o per l&#8217;accertamento, l&#8217;esercizio o la difesa di diritti legali o per la tutela dei diritti di un&#8217;altra persona fisica o giuridica o per motivi di rilevante interesse pubblico dell&#8217;Unione Europea o di uno Stato membro.<\/p>\n<h3 style=\"text-align: left;\">Crittografia SSL o TLS<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Questo sito utilizza la crittografia SSL o TLS per motivi di sicurezza e per proteggere la trasmissione di contenuti riservati, come gli ordini o le richieste di informazioni che ci invii in qualit\u00e0 di gestore del sito.<br \/>\nPuoi riconoscere una connessione crittografata dal fatto che la riga dell&#8217;indirizzo del browser passa da &#8222;http:\/\/&#8220; a &#8222;https:\/\/&#8220; e dal simbolo del lucchetto nella riga del browser. <\/p>\n<p style=\"text-align: left;\">Se la crittografia SSL o TLS \u00e8 attivata, i dati che ci trasmetti non possono essere letti da terzi.<\/p>\n<h2 style=\"text-align: left;\">4. raccolta di dati su questo sito web<\/h2>\n<h3 style=\"text-align: left;\">Biscotti<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Le nostre pagine Internet utilizzano i cosiddetti &#8222;cookie&#8220;. I cookie sono piccoli pacchetti di dati e non causano alcun danno al tuo dispositivo finale. Vengono memorizzati temporaneamente per la durata di una sessione (cookie di sessione) o permanentemente (cookie permanenti) sul tuo dispositivo finale. I cookie di sessione vengono eliminati automaticamente al termine della visita. I cookie permanenti rimangono memorizzati sul tuo dispositivo finale finch\u00e9 non li cancelli tu stesso o finch\u00e9 non vengono eliminati automaticamente dal tuo browser web.<\/p>\n<p style=\"text-align: left;\">I cookie hanno diverse funzioni. Molti cookie sono tecnicamente necessari, in quanto alcune funzioni del sito web non funzionano senza di essi (ad esempio la funzione del carrello della spesa o la visualizzazione di video). <br \/>Altri cookie possono essere utilizzati per analizzare il comportamento degli utenti o per scopi pubblicitari. I cookie possono provenire da noi (cookie di prima parte) o da societ\u00e0 terze (i cosiddetti cookie di terze parti). I cookie di terze parti consentono l&#8217;integrazione di alcuni servizi di aziende terze all&#8217;interno dei siti web (ad esempio, i cookie per l&#8217;elaborazione dei servizi di pagamento).<\/p>\n<p style=\"text-align: left;\">I cookie che sono necessari per eseguire il processo di comunicazione elettronica, per fornire alcune funzioni che hai richiesto (ad esempio, per la funzione del carrello della spesa) o per ottimizzare il sito web (ad esempio, i cookie per misurare l&#8217;audience del web) (cookie necessari) sono memorizzati sulla base dell&#8217;art. 6 par. 1 lit. a GDPR. 1 lit. <br \/>f GDPR, a meno che non sia specificata un&#8217;altra base giuridica. L&#8217;operatore del sito web ha un interesse legittimo nella memorizzazione dei cookie necessari per la fornitura tecnicamente priva di errori e ottimizzata dei suoi servizi. Se \u00e8 stato richiesto il consenso alla memorizzazione di cookie e tecnologie di riconoscimento comparabili, il trattamento viene effettuato esclusivamente sulla base di tale consenso (art. 6 par. 1 lett. a GDPR e \u00a7 25 par. 1 TTDSG); il consenso pu\u00f2 essere revocato in qualsiasi momento.<\/p>\n<p style=\"text-align: left;\">Puoi impostare il tuo browser in modo da essere informato sull&#8217;impostazione dei cookie e consentire i cookie solo in singoli casi, escludere l&#8217;accettazione dei cookie per determinati casi o in generale e attivare la cancellazione automatica dei cookie alla chiusura del browser.<br \/>\nSe i cookie vengono disattivati, le funzionalit\u00e0 di questo sito web potrebbero essere limitate. <\/p>\n<p style=\"text-align: left;\">Puoi scoprire quali sono i cookie e i servizi utilizzati da questo sito web nella presente informativa sulla privacy.<\/p>\n<h3 style=\"text-align: left;\">Biscotti Borlabs<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">\n<p>Questo sito web utilizza il Cookie Borlabs, che imposta un cookie tecnicamente necessario<em>(borlabs-cookie<\/em>) per memorizzare i tuoi consensi sui cookie. Il Cookie Borlabs non tratta alcun dato personale. Il cookie<em>borlabs-cookie<\/em> memorizza i consensi che hai dato quando sei entrato nel sito web. Se desideri revocare questo consenso, \u00e8 sufficiente cancellare il cookie nel tuo browser. Quando rientri\/ricarichi il sito web, ti verr\u00e0 chiesto nuovamente il consenso per i cookie.<\/p>\n<h3 style=\"text-align: left;\">Richiesta via e-mail, telefono o fax<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Se ci contatti via e-mail, telefono o fax, la tua richiesta, compresi tutti i dati personali (nome, richiesta), verr\u00e0 memorizzata ed elaborata da noi allo scopo di elaborare la tua richiesta.<br \/>\nNon trasmetteremo questi dati senza il tuo consenso. <\/p>\n<p style=\"text-align: left;\">Questi dati sono trattati sulla base dell&#8217;Art. 6 para. 1 lit. b GDPR, nella misura in cui la tua richiesta sia legata all&#8217;adempimento di un contratto o sia necessaria per l&#8217;attuazione di misure precontrattuali. In tutti gli altri casi, il trattamento si basa sul nostro legittimo interesse a trattare efficacemente le richieste di informazioni che ci vengono rivolte (art. 6 par. 1 lett. f GDPR) o sul tuo consenso (art. 6 par. 1 lett. a GDPR) se questo \u00e8 stato richiesto; il consenso pu\u00f2 essere revocato in qualsiasi momento.<\/p>\n<p style=\"text-align: left;\">I dati che ci invii tramite le richieste di contatto rimarranno presso di noi fino a quando non ci chiederai di cancellarli, non revocherai il tuo consenso alla conservazione o lo scopo della conservazione dei dati non sar\u00e0 pi\u00f9 valido (ad esempio, dopo che la tua richiesta \u00e8 stata elaborata).<br \/>\nLe disposizioni di legge obbligatorie, in particolare i periodi di conservazione previsti dalla legge, rimangono inalterate. <\/p>\n<h3 style=\"text-align: left;\">Modulo di contatto<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Se ci invii richieste di informazioni tramite il modulo di contatto, i tuoi dati dal modulo di richiesta, compresi i dati di contatto che ci fornisci, saranno conservati da noi allo scopo di elaborare la richiesta e in caso di domande successive. Non trasmetteremo questi dati senza il tuo consenso. <\/p>\n<p style=\"text-align: left;\">Questi dati sono trattati sulla base dell&#8217;Art. 6 para. 1 lit. b GDPR, nella misura in cui la tua richiesta sia legata all&#8217;adempimento di un contratto o sia necessaria per l&#8217;attuazione di misure precontrattuali. In tutti gli altri casi, il trattamento si basa sul nostro legittimo interesse a trattare efficacemente le richieste di informazioni che ci vengono rivolte (art. 6 par. 1 lett. f GDPR) o sul tuo consenso (art. 6 par. 1 lett. a GDPR) se questo \u00e8 stato richiesto; il consenso pu\u00f2 essere revocato in qualsiasi momento.<\/p>\n<p style=\"text-align: left;\">Conserveremo i dati da te forniti nel modulo di contatto fino a quando non ne richiederai la cancellazione, non revocherai il tuo consenso alla loro conservazione o non verr\u00e0 meno lo scopo per cui sono stati conservati (ad esempio, dopo aver soddisfatto la tua richiesta). Le disposizioni di legge obbligatorie, in particolare i periodi di conservazione, rimangono inalterate. <\/p>\n<h3 style=\"text-align: left;\">Google Analytics 4<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Questo sito web utilizza Google Analytics 4, un servizio di analisi web di Google Ireland Limited, Gordon House, 4 <em>Barrow<\/em> St, Dublin, D04 E5W5, Ireland (&#8222;Google&#8220;), che consente di analizzare il tuo utilizzo del nostro sito web.<\/p>\n<p style=\"text-align: left;\">Per impostazione predefinita, quando visiti il sito web vengono impostati 4 cookie da Google Analytics, che vengono memorizzati come piccoli moduli di testo sul tuo dispositivo finale e raccolgono determinate informazioni. L&#8217;ambito di queste informazioni comprende anche il tuo indirizzo IP, che tuttavia viene abbreviato da Google con le ultime cifre per escludere un riferimento personale diretto.<\/p>\n<p style=\"text-align: left;\">Le informazioni vengono trasferite ai server di Google e l\u00ec elaborate. Sono possibili anche trasmissioni a Google LLC, con sede negli Stati Uniti.<\/p>\n<p style=\"text-align: left;\">Google utilizza le informazioni raccolte per nostro conto per analizzare l&#8217;utilizzo del sito web da parte degli utenti, per compilare report sulle attivit\u00e0 del sito web e per fornire altri servizi relativi alle attivit\u00e0 del sito web e all&#8217;utilizzo di internet. L&#8217;indirizzo IP abbreviato trasmesso dal tuo browser nell&#8217;ambito di Google Analytics non verr\u00e0 unito ad altri dati di Google. I dati raccolti nell&#8217;ambito dell&#8217;utilizzo di Google Analytics 4 vengono conservati per un periodo di due mesi e poi cancellati.<\/p>\n<p style=\"text-align: left;\">Tutti i trattamenti sopra descritti, in particolare l&#8217;impostazione dei cookie sul dispositivo finale utilizzato, avranno luogo solo se ci avrai dato il tuo consenso esplicito ai sensi dell&#8217;art. 6 par. 1 lit. f GDPR. Art. 6 par. 1 lit. GDPR hanno concesso.<\/p>\n<p style=\"text-align: left;\">Senza il tuo consenso, Google Analytics 4 non verr\u00e0 utilizzato durante la tua visita al nostro sito web. Puoi revocare il tuo consenso in qualsiasi momento con effetto per il futuro. Per esercitare il tuo diritto di cancellazione, ti preghiamo di disattivare questo servizio utilizzando lo &#8222;strumento di consenso ai cookie&#8220; fornito sul sito web.<\/p>\n<p style=\"text-align: left;\">Ulteriori informazioni legali su Google Analytics 4 sono disponibili su <a href=\"https:\/\/policies.google.com\/privacy?hl=de&amp;gl=de\">https:\/\/policies.google.com\/privacy?hl=de&amp;gl=de<\/a> e su <a href=\"https:\/\/policies.google.com\/technologies\/partner-sites\">https:\/\/policies.google.com\/technologies\/partner-sites<\/a>.<\/p>\n<h3 style=\"text-align: left;\">Caratteristiche demografiche<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Google Analytics 4 utilizza la funzione speciale &#8222;caratteristiche demografiche&#8220; e pu\u00f2 utilizzarla per creare delle statistiche che fanno riferimento all&#8217;et\u00e0, al sesso e agli interessi dei visitatori del sito. Questo avviene attraverso l&#8217;analisi della pubblicit\u00e0 e delle informazioni provenienti da fornitori terzi. In questo modo \u00e8 possibile identificare i gruppi target per le attivit\u00e0 di marketing. Tuttavia, i dati raccolti non possono essere assegnati a una persona specifica e saranno cancellati dopo un periodo di conservazione di due mesi.<\/p>\n<h3 style=\"text-align: left;\">Segnali di Google<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Come estensione di Google Analytics 4, Google Signals pu\u00f2 essere utilizzato su questo sito web per generare rapporti cross-device. Se hai attivato annunci personalizzati e hai collegato i tuoi dispositivi al tuo account Google, Google pu\u00f2 utilizzare i tuoi dati personali a tale scopo, previo tuo consenso all&#8217;utilizzo di Google Analytics ai sensi dell&#8217;art. 6 par. 1 lett. f GDPR. Art. 6 par. 1 lit. a GDPR per analizzare il tuo comportamento d&#8217;uso tra i vari dispositivi e creare modelli di database, anche per le conversioni cross-device. Non riceviamo alcun dato personale da Google, ma solo statistiche. Se vuoi interrompere l&#8217;analisi cross-device, puoi disattivare la funzione &#8222;Pubblicit\u00e0 personalizzata&#8220; nelle impostazioni del tuo account Google. Segui le istruzioni riportate in questa pagina: <a href=\"https:\/\/support.google.com\/ads\/answer\/2662922?hl=de\">https:\/\/support.google.com\/ads\/answer\/2662922?hl=de<\/a> Ulteriori informazioni sui segnali di Google sono disponibili al seguente link: <a href=\"https:\/\/support.google.com\/analytics\/answer\/7532985?hl=de\">https:\/\/support.google.com\/analytics\/answer\/7532985?hl=de<\/a><\/p>\n<h3 style=\"text-align: left;\">ID utente<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Come estensione di Google Analytics 4, su questo sito web \u00e8 possibile utilizzare la funzione &#8222;UserIDs&#8220;. Se hai acconsentito all&#8217;utilizzo di Google Analytics 4 acc. Art. 6 par. 1 lit. a GDPR, hai creato un account su questo sito web e accedi con questo account su diversi dispositivi, le tue attivit\u00e0, comprese le conversioni, possono essere analizzate tra i vari dispositivi.<\/p>\n<p style=\"text-align: left;\">Per i trasferimenti di dati verso gli Stati Uniti, il fornitore ha aderito al Data Privacy Framework UE-USA, che garantisce il rispetto del livello europeo di protezione dei dati sulla base di una decisione di adeguatezza della Commissione Europea.<\/p>\n<h3 class=\"p-rich_text_section\" style=\"text-align: left;\">Google Ads (ex Google Adwords)<\/h3>\n<p class=\"p-rich_text_section\" style=\"text-align: left;\">Informazioni\/scopo:<\/p>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Informazioni\/scopo: Google Ads Conversion Utilizziamo il servizio Google Ads Conversion per attirare l&#8217;attenzione sulle nostre interessanti offerte con l&#8217;aiuto di materiale pubblicitario (i cosiddetti Google Ads) su siti web esterni. Possiamo determinare il successo delle singole misure pubblicitarie in relazione ai dati della campagna pubblicitaria. Siamo interessati a mostrarti annunci pubblicitari di tuo interesse, a rendere il nostro sito web pi\u00f9 interessante per te e a calcolare in modo equo i costi pubblicitari. Questi annunci vengono forniti da Google tramite i cosiddetti &#8222;server pubblicitari&#8220;. A tal fine, utilizziamo i cookie degli ad server, che possono essere utilizzati per misurare alcuni parametri di successo, come la visualizzazione degli annunci o i clic degli utenti. Se accedi al nostro sito web tramite un annuncio di Google, Google Ads memorizzer\u00e0 un cookie sul tuo dispositivo finale. L&#8217;ID univoco del cookie, il numero di impressioni pubblicitarie per posizionamento (frequenza), l&#8217;ultima impressione (rilevante per le conversioni successive alla visualizzazione) e le informazioni di opt-out (che indicano che un utente non desidera pi\u00f9 essere indirizzato) sono solitamente memorizzati come valori di analisi per questo cookie, che consentono a Google di riconoscere il tuo browser Internet. Se un utente visita determinate pagine del sito web dei clienti di Ads e il cookie memorizzato sul suo computer non \u00e8 ancora scaduto, Google e i clienti possono riconoscere che l&#8217;utente ha cliccato sull&#8217;annuncio ed \u00e8 stato reindirizzato a questa pagina. Ogni cliente di Ads riceve un cookie diverso. I cookie non possono quindi essere tracciati attraverso i siti web dei clienti di Ads. Noi stessi non raccogliamo e trattiamo alcun dato personale nell&#8217;ambito delle suddette misure pubblicitarie. Riceviamo solo analisi statistiche da Google. Sulla base di queste analisi, possiamo identificare quali misure pubblicitarie sono particolarmente efficaci. Non riceviamo ulteriori dati dall&#8217;utilizzo del materiale pubblicitario; in particolare, non possiamo identificare gli utenti sulla base di queste informazioni. Grazie agli strumenti di marketing utilizzati, il tuo browser stabilisce automaticamente una connessione diretta con il server di Google. Non abbiamo alcuna influenza sulla portata e sull&#8217;ulteriore utilizzo dei dati raccolti da Google attraverso l&#8217;uso di questo strumento e pertanto ti informiamo in base al nostro stato di conoscenza: attraverso l&#8217;integrazione di Ads Conversion, Google riceve l&#8217;informazione che hai richiamato la parte corrispondente del nostro sito web o hai cliccato su un nostro annuncio. Se sei registrato con un servizio Google, Google pu\u00f2 assegnare la visita al tuo account. Anche se non sei registrato su Google o non hai effettuato il login, \u00e8 possibile che Google scopra il tuo indirizzo IP e lo memorizzi.<\/p>\n<p style=\"text-align: left;\">Remarketing di Google Ads<\/p>\n<p style=\"text-align: left;\">Utilizziamo la funzione di remarketing del servizio Google Ads. Con la funzione di remarketing possiamo presentare agli utenti del nostro sito web annunci pubblicitari basati sui loro interessi su altri siti web della rete pubblicitaria di Google (in Google Search o su YouTube, i cosiddetti &#8222;Annunci Google&#8220; o su altri siti web). A tal fine, viene analizzata l&#8217;interazione degli utenti sul nostro sito web, ad esempio le offerte a cui l&#8217;utente era interessato, per poter mostrare agli utenti pubblicit\u00e0 mirata su altre pagine anche dopo che hanno visitato il nostro sito web. A tal fine, Google memorizza i cookie sui dispositivi finali degli utenti che visitano determinati servizi Google o siti web della Rete Display di Google. Questi cookie vengono utilizzati per registrare le visite di questi utenti. I cookie vengono utilizzati per identificare in modo univoco un browser web su uno specifico dispositivo finale e non per identificare una persona.<\/p>\n<p style=\"text-align: left;\">Principale fornitore di servizi: Google Ireland Ltd, Gordon House, Barrow Street, Dublino 4, Irlanda Sono possibili trasferimenti verso paesi terzi. Sono state stipulate clausole contrattuali standard ai sensi dell&#8217;art. 46 del GDPR come garanzia adeguata. Per i paesi terzi\/aziende per i quali esiste una decisione di adeguatezza, si applica anche la decisione di adeguatezza. Per ulteriori informazioni (come una copia delle garanzie), ti preghiamo di utilizzare i dettagli di contatto forniti.<\/p>\n<h2 style=\"text-align: left;\">5. social media<\/h2>\n<h3 style=\"text-align: left;\">Facebook<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Su questo sito sono integrati elementi del social network Facebook. Il fornitore di questo servizio \u00e8 Meta Platforms Ireland Limited, 4 Grand Canal Square, Dublino 2, Irlanda. Tuttavia, secondo Facebook, i dati raccolti vengono trasferiti anche negli Stati Uniti e in altri paesi terzi.<\/p>\n<p style=\"text-align: left;\">Puoi trovare una panoramica degli elementi dei social media di Facebook qui: <a href=\"https:\/\/developers.facebook.com\/docs\/plugins\/?locale=de_DE\">https:\/\/developers.facebook.com\/docs\/plugins\/?locale=de_DE<\/a>.<\/p>\n<p style=\"text-align: left;\">Quando l&#8217;elemento social media \u00e8 attivo, viene stabilita una connessione diretta tra il tuo dispositivo e il server di Facebook. Facebook riceve quindi l&#8217;informazione che l&#8217;utente ha visitato questo sito web con il suo indirizzo IP. Se clicchi sul &#8222;pulsante Mi piace&#8220; di Facebook mentre sei connesso al tuo account Facebook, puoi collegare i contenuti di questo sito web al tuo profilo Facebook. Questo permette a Facebook di associare la tua visita a questo sito web con il tuo account utente. Desideriamo sottolineare che noi, in quanto fornitori delle pagine, non siamo a conoscenza del contenuto dei dati trasmessi n\u00e9 del loro utilizzo da parte di Facebook. Ulteriori informazioni in merito sono disponibili nell&#8217;informativa sulla privacy di Facebook all&#8217;indirizzo: <a href=\"https:\/\/de-de.facebook.com\/privacy\/explanation\">https:\/\/de-de.facebook.com\/privacy\/explanation<\/a>.<\/p>\n<p style=\"text-align: left;\">Nella misura in cui \u00e8 stato ottenuto il consenso, l&#8217;utilizzo del suddetto servizio si basa sull&#8217;art. 6, comma 1, del Codice Civile. 1 lit. a GDPR e \u00a7 25 TTDSG. Il consenso pu\u00f2 essere revocato in qualsiasi momento. Se non \u00e8 stato ottenuto il consenso, il servizio viene utilizzato sulla base del nostro legittimo interesse a ottenere la pi\u00f9 ampia visibilit\u00e0 possibile sui social media.<\/p>\n<p style=\"text-align: left;\">Nella misura in cui i dati personali vengono raccolti sul nostro sito web con l&#8217;aiuto dello strumento qui descritto e trasmessi a Facebook, noi e Meta Platforms Ireland Limited, 4 Grand Canal Square, Grand Canal Harbour, Dublino 2, Irlanda siamo congiuntamente responsabili di questo trattamento dei dati (Art. 26 GDPR). La responsabilit\u00e0 congiunta \u00e8 limitata esclusivamente alla raccolta dei dati e al loro trasferimento a Facebook. Il trattamento effettuato da Facebook dopo l&#8217;inoltro non rientra nella responsabilit\u00e0 comune. Gli obblighi che ci incombono congiuntamente sono stati definiti in un accordo sul trattamento congiunto. Il testo dell&#8217;accordo \u00e8 disponibile all&#8217;indirizzo: <a href=\"https:\/\/www.facebook.com\/legal\/controller_addendum\">https:\/\/www.facebook.com\/legal\/controller_addendum<\/a>. In base a questo accordo, siamo responsabili di fornire le informazioni sulla protezione dei dati quando si utilizza lo strumento di Facebook e dell&#8217;implementazione sicura dello strumento sul nostro sito web in conformit\u00e0 con la legge sulla protezione dei dati. Facebook \u00e8 responsabile della sicurezza dei dati dei prodotti Facebook. Puoi far valere i diritti degli interessati (ad es. richieste di informazioni) in merito ai dati trattati da Facebook direttamente con Facebook. Se fai valere i tuoi diritti di interessato presso di noi, siamo obbligati a trasmetterli a Facebook.<\/p>\n<p style=\"text-align: left;\">Il trasferimento dei dati verso gli Stati Uniti si basa sulle clausole contrattuali standard della Commissione UE. I dettagli sono disponibili qui: <a href=\"https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum\">https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum<\/a>, <a href=\"https:\/\/de-de.facebook.com\/help\/566994660333381\">https:\/\/de-de.facebook.com\/help\/566994660333381<\/a> e <a href=\"https:\/\/www.facebook.com\/policy.php\">https:\/\/www.facebook.com\/policy.php<\/a>.<\/p>\n<h3 style=\"text-align: left;\">Instagram<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Le funzioni del servizio Instagram sono integrate in questo sito web. Queste funzioni sono offerte da Meta Platforms Ireland Limited, 4 Grand Canal Square, Grand Canal Harbour, Dublino 2, Irlanda.<\/p>\n<p style=\"text-align: left;\">Quando l&#8217;elemento social media \u00e8 attivo, viene stabilita una connessione diretta tra il tuo dispositivo e il server di Instagram. Instagram riceve quindi informazioni sulla tua visita a questo sito web.<\/p>\n<p style=\"text-align: left;\">Se hai effettuato l&#8217;accesso al tuo account Instagram, puoi collegare il contenuto di questo sito web al tuo profilo Instagram cliccando sul pulsante Instagram. Ci\u00f2 consente a Instagram di associare la tua visita a questo sito web al tuo account utente. Desideriamo sottolineare che, in qualit\u00e0 di fornitore delle pagine, non siamo a conoscenza del contenuto dei dati trasmessi o del loro utilizzo da parte di Instagram.<\/p>\n<p style=\"text-align: left;\">Nella misura in cui \u00e8 stato ottenuto il consenso, l&#8217;utilizzo del suddetto servizio si basa sull&#8217;art. 6, comma 1, del Codice Civile. 1 lit. a GDPR e \u00a7 25 TTDSG. Il consenso pu\u00f2 essere revocato in qualsiasi momento. Se non \u00e8 stato ottenuto il consenso, il servizio viene utilizzato sulla base del nostro legittimo interesse a ottenere la pi\u00f9 ampia visibilit\u00e0 possibile sui social media.<\/p>\n<p style=\"text-align: left;\">Nella misura in cui i dati personali vengono raccolti sul nostro sito web utilizzando lo strumento qui descritto e inoltrati a Facebook o Instagram, noi e Meta Platforms Ireland Limited, 4 Grand Canal Square, Grand Canal Harbour, Dublino 2, Irlanda siamo congiuntamente responsabili di questo trattamento dei dati (Art. 26 GDPR). La responsabilit\u00e0 congiunta \u00e8 limitata esclusivamente alla raccolta dei dati e al loro trasferimento a Facebook o Instagram. Il trattamento effettuato da Facebook o Instagram dopo l&#8217;inoltro non rientra nella responsabilit\u00e0 comune. Gli obblighi che ci incombono congiuntamente sono stati definiti in un accordo sul trattamento congiunto. Il testo dell&#8217;accordo \u00e8 disponibile all&#8217;indirizzo: <a href=\"https:\/\/www.facebook.com\/legal\/controller_addendum\">https:\/\/www.facebook.com\/legal\/controller_addendum<\/a>. In base a questo accordo, siamo responsabili di fornire le informazioni sulla protezione dei dati quando si utilizza lo strumento di Facebook o Instagram e dell&#8217;implementazione sicura dello strumento sul nostro sito web in conformit\u00e0 con la legge sulla protezione dei dati. Facebook \u00e8 responsabile della sicurezza dei dati dei prodotti Facebook e Instagram. Puoi far valere i diritti degli interessati (ad es. richieste di informazioni) in merito ai dati trattati da Facebook o Instagram direttamente con Facebook. Se fai valere i tuoi diritti di interessato presso di noi, siamo obbligati a trasmetterli a Facebook.<\/p>\n<p style=\"text-align: left;\">Il trasferimento dei dati verso gli Stati Uniti si basa sulle clausole contrattuali standard della Commissione UE. I dettagli sono disponibili qui: <a href=\"https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum\">https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum<\/a>, <a href=\"https:\/\/help.instagram.com\/519522125107875\">https:\/\/help.instagram.com\/519522125107875<\/a> e <a href=\"https:\/\/de-de.facebook.com\/help\/566994660333381\">https:\/\/de-de.facebook.com\/help\/566994660333381<\/a>.<\/p>\n<p style=\"text-align: left;\">Puoi trovare maggiori informazioni in merito nell&#8217;informativa sulla privacy di Instagram: <a href=\"https:\/\/instagram.com\/about\/legal\/privacy\/\">https:\/\/instagram.com\/about\/legal\/privacy\/<\/a>.<\/p>\n<h2 style=\"text-align: left;\">6. plugin e strumenti<\/h2>\n<h3 style=\"text-align: left;\">YouTube con protezione estesa dei dati<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Questo sito web incorpora video dal sito web di YouTube. Il gestore delle pagine \u00e8 Google Ireland Limited (&#8222;Google&#8220;), Gordon House, Barrow Street, Dublino 4, Irlanda.<\/p>\n<p style=\"text-align: left;\">Utilizziamo YouTube in modalit\u00e0 di protezione dei dati estesa.<br \/>\nSecondo YouTube, questa modalit\u00e0 significa che YouTube non memorizza alcuna informazione sui visitatori di questo sito web prima che questi guardino il video.<br \/>\nTuttavia, il trasferimento di dati ai partner di YouTube non \u00e8 necessariamente escluso dalla modalit\u00e0 di protezione estesa dei dati.<br \/>\nAd esempio, YouTube stabilisce una connessione con la rete Google DoubleClick indipendentemente dal fatto che l&#8217;utente guardi un video.   <\/p>\n<p style=\"text-align: left;\">Non appena avvii un video di YouTube su questo sito, viene stabilita una connessione ai server di YouTube.<br \/>\nQuesto comunica al server di YouTube quali pagine hai visitato.<br \/>\nSe sei connesso al tuo account YouTube, permetti a YouTube di assegnare il tuo comportamento di navigazione direttamente al tuo profilo personale.<br \/>\nPuoi evitare che ci\u00f2 accada disconnettendoti dal tuo account YouTube.   <\/p>\n<p style=\"text-align: left;\">Inoltre, YouTube pu\u00f2 memorizzare diversi cookie sul dispositivo finale dell&#8217;utente dopo l&#8217;avvio di un video o utilizzare tecnologie di riconoscimento analoghe (ad esempio, l&#8217;impronta digitale del dispositivo). In questo modo, YouTube pu\u00f2 ottenere informazioni sui visitatori di questo sito web. Queste informazioni vengono utilizzate, tra le altre cose, per registrare statistiche sui video, migliorare la facilit\u00e0 d&#8217;uso e prevenire tentativi di frode.<\/p>\n<p style=\"text-align: left;\">Dopo l&#8217;avvio di un video di YouTube, possono essere avviate ulteriori operazioni di elaborazione dei dati sulle quali non abbiamo alcuna influenza.<\/p>\n<p style=\"text-align: left;\">L&#8217;utilizzo di YouTube \u00e8 finalizzato a una presentazione accattivante delle nostre offerte online. Ci\u00f2 costituisce un interesse legittimo ai sensi dell&#8217;art. 6, comma 1, lettera a). 1 lit.<br \/>\nf GDPR.  Se \u00e8 stato richiesto un consenso corrispondente, il trattamento viene effettuato esclusivamente sulla base dell&#8217;Art. 6 para. 1 lit. a GDPR e \u00a7 25 para. 1 TTDSG, nella misura in cui il consenso includa la memorizzazione di cookie o l&#8217;accesso a informazioni nel dispositivo finale dell&#8217;utente (ad esempio, l&#8217;impronta digitale del dispositivo) ai sensi del TTDSG. Il consenso pu\u00f2 essere revocato in qualsiasi momento.<\/p>\n<p style=\"text-align: left;\">Puoi trovare maggiori informazioni sulla protezione dei dati su YouTube nella loro informativa sulla privacy all&#8217;indirizzo: <a href=\"https:\/\/policies.google.com\/privacy?hl=de\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<h3 style=\"text-align: left;\">Google Fonts (hosting locale)<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Questo sito utilizza i cosiddetti Google Fonts, forniti da Google, per la visualizzazione standardizzata dei caratteri. I font di Google sono installati localmente. La connessione ai server di Google non avviene.<\/p>\n<p style=\"text-align: left;\">Ulteriori informazioni su Google Fonts sono disponibili all&#8217;indirizzo <a href=\"https:\/\/developers.google.com\/fonts\/faq\">https:\/\/developers.google.com\/fonts\/faq<\/a> e nell&#8217;informativa sulla privacy di Google: <a href=\"https:\/\/policies.google.com\/privacy?hl=de\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<h3 style=\"text-align: left;\">Font Awesome (hosting locale)<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Questo sito utilizza Font Awesome per la visualizzazione standardizzata dei font. Font Awesome \u00e8 installato localmente. Una connessione ai server di Fonticons, Inc. non ha luogo.<\/p>\n<p style=\"text-align: left;\">Ulteriori informazioni su Font Awesome sono disponibili nell&#8217;informativa sulla privacy di Font Awesome all&#8217;indirizzo: <a href=\"https:\/\/fontawesome.com\/privacy\">https:\/\/fontawesome.com\/privacy<\/a>.<\/p>\n<h3 style=\"text-align: left;\">Google Maps<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Questo sito utilizza il servizio di mappe Google Maps. Il fornitore \u00e8 Google Ireland Limited (&#8222;Google&#8220;), Gordon House, Barrow Street, Dublino 4, Irlanda.<\/p>\n<p style=\"text-align: left;\">Per utilizzare le funzioni di Google Maps, \u00e8 necessario salvare il tuo indirizzo IP. Queste informazioni vengono solitamente trasferite a un server di Google negli Stati Uniti e l\u00ec memorizzate. Il fornitore di questo sito non ha alcuna influenza su questa trasmissione di dati. Se Google Maps \u00e8 attivato, Google pu\u00f2 utilizzare Google Fonts per la rappresentazione uniforme dei caratteri. Quando richiami Google Maps, il tuo browser carica i font web necessari nella cache del browser per visualizzare correttamente i testi e i caratteri.<\/p>\n<p style=\"text-align: left;\">L&#8217;utilizzo di Google Maps \u00e8 finalizzato a una presentazione accattivante delle nostre offerte online e a facilitare la ricerca dei luoghi che indichiamo sul sito. Ci\u00f2 costituisce un interesse legittimo ai sensi dell&#8217;art. 6, comma 1, lettera a). 1 lit.<br \/>\nf GDPR.  Se \u00e8 stato richiesto un consenso corrispondente, il trattamento viene effettuato esclusivamente sulla base dell&#8217;Art. 6 para. 1 lit. a GDPR e \u00a7 25 para. 1 TTDSG, nella misura in cui il consenso includa la memorizzazione di cookie o l&#8217;accesso a informazioni nel dispositivo finale dell&#8217;utente (ad esempio, l&#8217;impronta digitale del dispositivo) ai sensi del TTDSG. Il consenso pu\u00f2 essere revocato in qualsiasi momento.<\/p>\n<p style=\"text-align: left;\">Il trasferimento dei dati verso gli Stati Uniti si basa sulle clausole contrattuali standard della Commissione UE. I dettagli sono disponibili qui: <a href=\"https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/\">https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/<\/a> e <a href=\"https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/sccs\/\">https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/sccs\/.<\/a><\/p>\n<p style=\"text-align: left;\">Puoi trovare maggiori informazioni sul trattamento dei dati degli utenti nell&#8217;informativa sulla privacy di Google: <a href=\"https:\/\/policies.google.com\/privacy?hl=de\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<h3 style=\"text-align: left;\">Captcha amichevole<\/h3>\n<p style=\"text-align: left;\" data-pm-slice=\"1 1 []\">Su questo sito web utilizziamo Friendly Captcha (di seguito &#8222;Friendly Captcha&#8220;).<br \/>\nIl fornitore \u00e8 Friendly Captcha GmbH, Am Anger 3-5, 82237 Woerthsee, Germania. <\/p>\n<p style=\"text-align: left;\">Il Friendly Captcha \u00e8 utilizzato per verificare se i dati inseriti su questo sito web (ad esempio in un modulo di contatto) sono stati inseriti da un essere umano o da un programma automatico. A tal fine, Friendly Captcha analizza il comportamento del visitatore del sito web in base a diverse caratteristiche. Friendly Captcha valuta diverse informazioni per l&#8217;analisi (ad esempio, indirizzo IP anonimo, referente, tempo di visita, ecc.) Ulteriori informazioni al riguardo sono disponibili all&#8217;indirizzo: <a href=\"https:\/\/friendlycaptcha.com\/legal\/privacy-end-users\/\">https:\/\/friendlycaptcha.com\/legal\/privacy-end-users\/<\/a>.<\/p>\n<p style=\"text-align: left;\">I dati sono conservati e analizzati sulla base dell&#8217;Art. 6 para. 1 lit. f GDPR. L&#8217;operatore del sito web ha un interesse legittimo a proteggere il proprio sito web da spionaggio automatico abusivo e SPAM. Se \u00e8 stato richiesto un consenso corrispondente, il trattamento viene effettuato esclusivamente sulla base dell&#8217;Art. 6 para. 1 lit. a GDPR e \u00a7 25 para. 1 TTDSG, nella misura in cui il consenso includa la memorizzazione di cookie o l&#8217;accesso a informazioni nel dispositivo finale dell&#8217;utente (ad esempio, l&#8217;impronta digitale del dispositivo) ai sensi del TTDSG. Il consenso pu\u00f2 essere revocato in qualsiasi momento.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informativa sulla privacy 1. la protezione dei dati in sintesi Informazioni generali Le seguenti informazioni forniscono una panoramica di ci\u00f2 che accade ai tuoi dati personali quando visiti questo sito web. I dati personali sono tutti i dati con i quali puoi essere identificato personalmente. Informazioni dettagliate sul tema della protezione dei dati sono disponibili nella nostra informativa sulla privacy riportata in calce al presente testo. Raccolta di dati su questo sito web Chi \u00e8 responsabile della raccolta dei dati su questo sito? Il trattamento dei dati su questo sito web \u00e8 effettuato dall&#8217;operatore del sito. Puoi trovare i loro dettagli di contatto nella sezione &#8222;Titolare del trattamento&#8220; di questa informativa sulla privacy. Come raccogliamo i tuoi dati? Da un lato, alcuni dati vengono raccolti automaticamente o con il tuo consenso dai nostri sistemi informatici quando visiti il sito web. Si tratta principalmente di dati tecnici (ad esempio il browser internet, il sistema operativo o l&#8217;ora di visualizzazione della pagina). Questi dati vengono raccolti automaticamente non appena accedi al sito, mentre i tuoi dati vengono raccolti quando ce li fornisci. Ad esempio, i dati inseriti dall&#8217;utente nel modulo di contatto. Per cosa utilizziamo i tuoi dati? Una parte dei dati [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-240008","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/teora-xr.de\/en\/wp-json\/wp\/v2\/pages\/240008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teora-xr.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/teora-xr.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/teora-xr.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teora-xr.de\/en\/wp-json\/wp\/v2\/comments?post=240008"}],"version-history":[{"count":10,"href":"https:\/\/teora-xr.de\/en\/wp-json\/wp\/v2\/pages\/240008\/revisions"}],"predecessor-version":[{"id":242279,"href":"https:\/\/teora-xr.de\/en\/wp-json\/wp\/v2\/pages\/240008\/revisions\/242279"}],"wp:attachment":[{"href":"https:\/\/teora-xr.de\/en\/wp-json\/wp\/v2\/media?parent=240008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}